{"id":684,"date":"2023-09-14T09:52:49","date_gmt":"2023-09-14T13:52:49","guid":{"rendered":"https:\/\/cmie.ca\/call-for-proposals\/"},"modified":"2025-07-22T13:11:43","modified_gmt":"2025-07-22T17:11:43","slug":"appels-a-propositions","status":"publish","type":"page","link":"https:\/\/cmie.ca\/fr\/appels-a-propositions\/","title":{"rendered":"Appels \u00e0 propositions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"684\" class=\"elementor elementor-684 elementor-26\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dedcaa e-flex e-con-boxed e-con e-parent\" data-id=\"4dedcaa\" data-element_type=\"container\" id=\"blue\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-236d505 elementor-widget elementor-widget-heading\" data-id=\"236d505\" data-element_type=\"widget\" id=\"gradient-text\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appels \u00e0 propositions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01d65d1 e-flex e-con-boxed e-con e-parent\" data-id=\"01d65d1\" data-element_type=\"container\" id=\"blue\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d84e438 e-con-full e-flex e-con e-child\" data-id=\"d84e438\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd79f2c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"bd79f2c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Fonds de D\u00e9veloppement offre un soutien financier aux innovateurs, aux d\u00e9veloppeurs et aux \u00e9tablissements universitaires au Canada, sp\u00e9cifiquement dans le domaine des technologies radiopharmaceutiques et des isotopes m\u00e9dicaux. Ce financement est con\u00e7u pour acc\u00e9l\u00e9rer la progression des programmes en phase de d\u00e9marrage, cr\u00e9ant ainsi un pipeline continu pour le d\u00e9veloppement et la commercialisation \u00e9ventuelle.<\/p><p>Le Fonds de D\u00e9veloppement dispose de 5 millions de dollars \u00e0 consacrer \u00e0 l\u2019avancement des technologies des isotopes m\u00e9dicaux au Canada. Le soutien aux projets individuels variera entre 50 000 et 500 000 $. Le Fonds de D\u00e9veloppement remboursera jusqu&rsquo;\u00e0 50% des co\u00fbts \u00e9ligibles du projet lorsqu&rsquo;au moins 50 % du projet est financ\u00e9 par des sources non gouvernementales f\u00e9d\u00e9rales. De plus, chaque projet doit impliquer activement au moins une petite et moyenne entreprise (PME).<\/p><p>Pour les programmes radiopharmaceutiques, nous recherchons des programmes allant de la phase pr\u00e9clinique de preuve de concept aux premiers essais cliniques et progressant jusqu&rsquo;\u00e0 l&rsquo;\u00e9tape de pr\u00e9-commercialisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-045e48c elementor-widget elementor-widget-spacer\" data-id=\"045e48c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d63826 e-con-full e-flex e-con e-child\" data-id=\"8d63826\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b89c546 elementor-widget elementor-widget-image\" data-id=\"b89c546\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"282\" src=\"https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-1024x282.png\" class=\"attachment-large size-large wp-image-2417\" alt=\"\" srcset=\"https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-1024x282.png 1024w, https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-300x83.png 300w, https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-768x212.png 768w, https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-1536x424.png 1536w, https:\/\/cmie.ca\/wp-content\/uploads\/2023\/11\/CMIE_DevFundLogo_EnglishFrench-1-2048x565.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d738e5 elementor-widget elementor-widget-text-editor\" data-id=\"1d738e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>APPEL \u00c0 PROPOSITIONS MAINTENANT OUVERT !<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e11275f e-flex e-con-boxed e-con e-parent\" data-id=\"e11275f\" data-element_type=\"container\" id=\"gradient\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6773dc9 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"6773dc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Notre premier appel \u00e0 propositions est maintenant ouvert!<\/h4>\n<p>La date limite de soumission des candidatures est le <strong>31 janvier 2024 \u00e0 23 h 59 (PST).<\/strong><\/p>\n<p>La premi\u00e8re s\u00e9rie de candidatures consiste en une pr\u00e9sentation PowerPoint <span style=\"color: #ff0000;\"><strong>non confidentielle<\/strong><\/span>. Des questions et des sujets ont \u00e9t\u00e9 inclus dans le mod\u00e8le de diapositives que les candidats doivent compl\u00e9ter (t\u00e9l\u00e9charger le document <em>Demande au fonds de d\u00e9veloppement <\/em>ci-dessous). Les candidatures doivent \u00eatre soumises au format PowerPoint, avec un maximum de 10 diapositives.<\/p>\n<p><strong>Les candidats peuvent contacter\u00a0<a href=\"mailto:funding@cmie.ca\" target=\"_blank\" rel=\"noopener\">funding@cmie.ca<\/a>\u00a0pour acc\u00e9der \u00e0 un lien s\u00e9curis\u00e9 pour soumettre leur candidature.<\/strong><\/p>\n<p>Lorsque vous remplissez votre candidature, soyez conscient des crit\u00e8res d&rsquo;\u00e9valuation que les \u00e9valuateurs utiliseront pour noter votre candidature (t\u00e9l\u00e9charger le document <em>Guide pour les candidatures<\/em> ci-dessous).<\/p>\n<p>Les candidats les mieux class\u00e9s seront contact\u00e9s le <strong>15 f\u00e9vrier 2024<\/strong>, o\u00f9 il leur sera demand\u00e9 de pr\u00e9parer une pr\u00e9sentation <span style=\"color: #ff0000;\"><strong>confidentielle<\/strong><\/span> d&rsquo;une heure au Comit\u00e9 de S\u00e9lection des Projets \u00c9ligibles qui d\u00e9crira plus en d\u00e9tail le projet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01758d0 elementor-widget elementor-widget-text-editor\" data-id=\"01758d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b><strong>Troisi\u00e8me appel \u00e0 propositions: d\u00e9sormais ouvert<\/strong><\/b><\/h2><p style=\"text-align: left;\">La date limite de soumission des candidatures est fix\u00e9e au <b><u>12 ao\u00fbt 2025 \u00e0 23 h 59, heure normale du Pacifique (PST)<\/u><\/b>.<\/p><p style=\"text-align: left;\">La premi\u00e8re phase consiste en une pr\u00e9sentation PowerPoint <b><u>non confidentielle<\/u><\/b>. Les questions et les th\u00e8mes \u00e0 aborder sont inclus dans le mod\u00e8le de pr\u00e9sentation que les candidats doivent remplir (t\u00e9l\u00e9charger le <b><i>formulaire de candidature CMIEDF <\/i><\/b>ci-dessous). Les candidatures doivent \u00eatre soumises au format PowerPoint et comporter au maximum <b><u>10 diapositives<\/u><\/b>.<\/p><p style=\"text-align: left;\">Lorsque vous remplissez le formulaire, veuillez prendre connaissance des crit\u00e8res d&rsquo;\u00e9valuation qui seront utilis\u00e9s par les examinateurs pour noter votre candidature (t\u00e9l\u00e9charger le document <b><i>\u00ab Guidelines for Applicants \u00bb<\/i><\/b> ci-dessous).<\/p><p style=\"text-align: left;\">Les candidats les mieux class\u00e9s seront contact\u00e9s le <b>22 septembre 2025<\/b> et invit\u00e9s \u00e0 pr\u00e9parer une pr\u00e9sentation <b><u>confidentielle <\/u><\/b>de trente minutes devant le comit\u00e9 de s\u00e9lection des projets \u00e9ligibles, afin de d\u00e9crire leur projet plus en d\u00e9tail.<\/p><p style=\"text-align: left;\"><b><u><strong>Documents cl\u00e9s :<\/strong><\/u><\/b><\/p><ul><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/CMIEDF-Application-ENGLISH.pptx\">CMIEDF Application ENGLISH<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/CMIEDF-Application-FRENCH.pptx\">CMIEDF Application FRENCH<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/Basic-Eligibility-Attestation-Form.docx\">Basic Eligibility Attestation Form<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/CMIEDF-Application-Guidelines-ENGLISH.docx\">Directives pour les candidatures au CMIEDF EN ANGLAIS<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/CMIEDF-Application-Guidelines-FRENCH.docx\">Directives pour les candidatures au CMIEDF EN FRAN\u00c7AIS<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/Frequently-Asked-Questions-ENGLISH.docx\">Foire aux questions EN ANGLAIS<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/wp-content\/uploads\/2025\/06\/Frequently-Asked-Questions-FRENCH.docx\">Foire aux questions EN FRAN\u00c7AIS<\/a><\/li><li style=\"text-align: left;\"><a href=\"https:\/\/cmie.ca\/ultimate-recipient-agreement-template-june-2025\/\">Mod\u00e8le d&rsquo;accord avec le b\u00e9n\u00e9ficiaire final \u2013 juin 2025<\/a><\/li><\/ul><p><b><u>Dates importantes :<\/u><\/b><\/p><p style=\"text-align: left;\"><strong>Ouverture de l&rsquo;appel \u00e0 propositions : 26 juin 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>Cl\u00f4ture de l&rsquo;appel \u00e0 propositions : 12 ao\u00fbt 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>Information des candidats retenus pour la deuxi\u00e8me \u00e9tape : 22 septembre 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>Date limite pour soumettre le rapport \u00e9crit et les diapositives confidentielles de pr\u00e9sentation : 30 octobre 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>Pr\u00e9sentation des projets : novembre 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>Information des candidats retenus pour b\u00e9n\u00e9ficier d&rsquo;un financement : 16 d\u00e9cembre 2025<\/strong><\/p><p style=\"text-align: left;\"><strong>D\u00e9but du financement : 1er janvier 2026<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33be94a elementor-widget elementor-widget-text-editor\" data-id=\"33be94a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSi vous avez des questions concernant le processus de candidature pour le Fonds de D\u00e9veloppement, veuillez nous contacter \u00e0 <span style=\"color: #ffffff;\"><strong><a style=\"color: #ffffff;\" href=\"mailto:funding@cmie.ca\">funding@cmie.ca<\/a><\/strong><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3baacc4 e-flex e-con-boxed e-con e-parent\" data-id=\"3baacc4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a89ae2 elementor-widget elementor-widget-heading\" data-id=\"2a89ae2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5223c8a elementor-widget elementor-widget-toggle\" data-id=\"5223c8a\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qui peut postuler?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8611\"><p>Cette candidature est ouverte aux petites et moyennes entreprises (PME), aux \u00e9tablissements universitaires, aux organismes \u00e0 but non lucratif, aux entreprises multinationales (EMN) et aux instituts de recherche canadiens. Chaque projet doit impliquer activement au moins une PME.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8612\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8612\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les filiales de grandes entreprises peuvent-elles poser leur candidature ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8612\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8612\"><p>Le Fonds de d\u00e9veloppement du \u00c9CIM vise \u00e0 favoriser la cr\u00e9ation de nouvelles entreprises et \u00e0 acc\u00e9l\u00e9rer la commercialisation des actifs canadiens dans l&rsquo;industrie des isotopes m\u00e9dicaux. Conform\u00e9ment \u00e0 cet objectif, nous donnerons la priorit\u00e9 aux demandes \u00e9manant d&rsquo;entreprises ind\u00e9pendantes qui ne sont pas des filiales de grandes entreprises.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8613\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8613\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels types de projets peuvent b\u00e9n\u00e9ficier d'un financement ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8613\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8613\"><p>Ce cycle de financement soutiendra les programmes de recherche sur les technologies radiopharmaceutiques et les isotopes m\u00e9dicaux. Nous recherchons des programmes avec des collaborations \u00e0 fort impact qui favorisent le d\u00e9veloppement d&rsquo;entreprises et de technologies en mettant l&rsquo;accent sur la commercialisation. Les programmes \u00e9ligibles peuvent se situer \u00e0 un niveau de maturit\u00e9 technologique (NMT) de 1 \u00e0 9.<\/p><p>Le \u00c9CIM est particuli\u00e8rement int\u00e9ress\u00e9 par les technologies innovantes en mati\u00e8re d&rsquo;isotopes m\u00e9dicaux qui aident \u00e0 diagnostiquer et \u00e0 traiter des maladies rares ou difficiles \u00e0 traiter.<\/p><p>En outre, le Fonds de d\u00e9veloppement du \u00c9CIM n&rsquo;accepte pas actuellement de propositions pour des \u00e9tudes exp\u00e9rimentales ou des rapports de cas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8614\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8614\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le montant du financement allou\u00e9 par projet ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8614\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8614\"><p>Le financement du programme peut \u00eatre demand\u00e9 entre\u00a0<strong>200 000 $\u00a0<\/strong>et\u00a0<strong>500 000 $<\/strong>. Le Fonds de D\u00e9veloppement remboursera jusqu\u2019\u00e0 50% des co\u00fbts \u00e9ligibles du projet lorsqu\u2019au moins 50% du projet est financ\u00e9 par des sources non gouvernementales f\u00e9d\u00e9rales.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8615\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8615\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce qu'un accord de b\u00e9n\u00e9ficiaire final et pourquoi dois-je le signer ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8615\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8615\"><p>L&rsquo;accord avec le b\u00e9n\u00e9ficiaire final (URA) est un contrat officiel entre les deux b\u00e9n\u00e9ficiaires principaux du \u00c9CIM (Centre for Probe Development and Commercialization et TRIUMF Innovations) et la partie qui re\u00e7oit le financement (le b\u00e9n\u00e9ficiaire final). Cet accord d\u00e9taille les obligations des b\u00e9n\u00e9ficiaires principaux et du b\u00e9n\u00e9ficiaire final concernant le projet admissible et le financement du projet, les demandes et les paiements, les rapports, le suivi, l&rsquo;audit et l&rsquo;\u00e9valuation, les d\u00e9clarations, les garanties et les engagements, la propri\u00e9t\u00e9 intellectuelle, la confidentialit\u00e9, la publicit\u00e9, l&rsquo;indemnisation et la limitation de la responsabilit\u00e9, les d\u00e9faillances et les recours, la dur\u00e9e, la r\u00e9siliation, la survie, les avis et les dispositions g\u00e9n\u00e9rales.<\/p><p>Les conditions \u00e9nonc\u00e9es dans l&rsquo;accord-cadre ne sont pas n\u00e9gociables. Il convient de les examiner attentivement avant de d\u00e9poser une demande de financement.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8616\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8616\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand ouvrira le prochain appel \u00e0 propositions?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8616\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8616\"><p>Le prochain appel \u00e0 propositions devrait \u00eatre lanc\u00e9 au printemps\/\u00e9t\u00e9 2025.<\/p><p>Les projets ne peuvent pas commencer avant la date d&rsquo;attribution et doivent se terminer au plus tard en mars 2026.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8617\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8617\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">O\u00f9 dois-je d\u00e9poser ma candidature ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8617\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8617\"><p>Toutes les candidatures doivent \u00eatre envoy\u00e9es \u00e0 <a href=\"mailto:funding@cmie.ca\">funding@cmie.ca<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-530e27a e-flex e-con-boxed e-con e-parent\" data-id=\"530e27a\" data-element_type=\"container\" id=\"gradient\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13bac0 elementor-widget elementor-widget-spacer\" data-id=\"e13bac0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23a1231 e-flex e-con-boxed e-con e-parent\" data-id=\"23a1231\" data-element_type=\"container\" id=\"newsletter\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6480d9 elementor-widget elementor-widget-heading\" data-id=\"a6480d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Faites partie de notre communaut\u00e9, c'est gratuit!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f0fb9d elementor-widget elementor-widget-text-editor\" data-id=\"6f0fb9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recevez les derni\u00e8res nouvelles et mises \u00e0 jour sur les appels de financement et les \u00e9v\u00e9nements<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ce75f1 e-flex e-con-boxed e-con e-parent\" data-id=\"9ce75f1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e17ea00 elementor-widget elementor-widget-wp-widget-gform_widget\" data-id=\"e17ea00\" data-element_type=\"widget\" data-widget_type=\"wp-widget-gform_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/dist\/dom-ready.min.js?ver=f77871ff7694fffea381\" id=\"wp-dom-ready-js\"><\/script>\n<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/dist\/hooks.min.js?ver=dd5603f07f9220ed27f1\" id=\"wp-hooks-js\"><\/script>\n<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/dist\/i18n.min.js?ver=c26c3dc7bed366793375\" id=\"wp-i18n-js\"><\/script>\n<script id=\"wp-i18n-js-after\">\nwp.i18n.setLocaleData( { 'text direction\\u0004ltr': [ 'ltr' ] } );\n\/\/# sourceURL=wp-i18n-js-after\n<\/script>\n<script id=\"wp-a11y-js-translations\">\n( function( domain, translations ) {\n\tvar localeData = translations.locale_data[ domain ] || translations.locale_data.messages;\n\tlocaleData[\"\"].domain = domain;\n\twp.i18n.setLocaleData( localeData, domain );\n} )( \"default\", {\"translation-revision-date\":\"2026-03-13 13:01:53+0000\",\"generator\":\"GlotPress\\\/4.0.3\",\"domain\":\"messages\",\"locale_data\":{\"messages\":{\"\":{\"domain\":\"messages\",\"plural-forms\":\"nplurals=2; plural=n > 1;\",\"lang\":\"fr\"},\"Notifications\":[\"Notifications\"]}},\"comment\":{\"reference\":\"wp-includes\\\/js\\\/dist\\\/a11y.js\"}} );\n\/\/# sourceURL=wp-a11y-js-translations\n<\/script>\n<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/dist\/a11y.min.js?ver=cb460b4676c94bd228ed\" id=\"wp-a11y-js\"><\/script>\n<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/jquery\/jquery.min.js?ver=3.7.1\" id=\"jquery-core-js\"><\/script>\n<script src=\"https:\/\/cmie.ca\/wp-includes\/js\/jquery\/jquery-migrate.min.js?ver=3.4.1\" id=\"jquery-migrate-js\"><\/script>\n<script defer='defer' src=\"https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\/js\/jquery.json.min.js?ver=2.10.1\" id=\"gform_json-js\"><\/script>\n<script id=\"gform_gravityforms-js-extra\">\nvar gf_global = {\"gf_currency_config\":{\"name\":\"Dollar canadien\",\"symbol_left\":\"$\",\"symbol_right\":\"CAD\",\"symbol_padding\":\" \",\"thousand_separator\":\",\",\"decimal_separator\":\".\",\"decimals\":2,\"code\":\"CAD\"},\"base_url\":\"https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\",\"number_formats\":[],\"spinnerUrl\":\"https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg\",\"version_hash\":\"486b84badd246bf5ee1c7e2f469ad9c4\",\"strings\":{\"newRowAdded\":\"Nouvelle ligne ajout\\u00e9e.\",\"rowRemoved\":\"Rang\\u00e9e supprim\\u00e9e\",\"formSaved\":\"Le formulaire a \\u00e9t\\u00e9 enregistr\\u00e9. Le contenu contient le lien pour retourner et terminer le formulaire.\"}};\n\/\/# sourceURL=gform_gravityforms-js-extra\n<\/script>\n<script defer='defer' src=\"https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\/js\/gravityforms.min.js?ver=2.10.1\" id=\"gform_gravityforms-js\"><\/script>\n<script defer='defer' src=\"https:\/\/www.google.com\/recaptcha\/api.js?hl=en&amp;ver=6.9.4#038;render=explicit\" id=\"gform_recaptcha-js\"><\/script>\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_1' ><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/pages\/684#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_above description_below validation_below'><div id=\"field_1_4\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_above gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'>X\/Twitter<\/label><div class='ginput_container'><input name='input_4' id='input_1_4' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_4'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/div><fieldset id=\"field_1_2\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-full gfield_contains_required field_sublabel_above gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nom<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Requis)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_2'>\n                            \n                            <span id='input_1_2_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_1_2_3' class='gform-field-label gform-field-label--type-sub '>Pr\u00e9nom<\/label>\n                                                    <input type='text' name='input_2.3' id='input_1_2_3' value=''   aria-required='true'    autocomplete=\"given-name\" \/>\n                                                <\/span>\n                            \n                            <span id='input_1_2_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_1_2_6' class='gform-field-label gform-field-label--type-sub '>Nom de famille<\/label>\n                                                            <input type='text' name='input_2.6' id='input_1_2_6' value=''   aria-required='true'    autocomplete=\"family-name\" \/>\n                                                        <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_1_1\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full gfield_contains_required field_sublabel_above gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>Adresse email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Requis)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_1' id='input_1_1' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_1_3\" class=\"gfield gfield--type-captcha gfield--input-type-captcha gfield--width-full field_sublabel_above gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_3'>CAPTCHA<\/label><div id='input_1_3' class='ginput_container ginput_recaptcha' data-sitekey='6Lcd45csAAAAANuGE-vVVSKiP_y8bOsSxea_O-fH'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Tiens-moi au courrant!'  \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=gravity-theme&amp;hash=558ec844cf7558a06fc9b5a822c5e4b5' \/><input type='hidden' class='gform_hidden' name='gform_submission_speeds' value='{&quot;pages&quot;:[]}' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CAD' value='\/mM53GacVHx6pMaTljgc4nUSDiS2jvQogACpcjQhY38GkUG3Zuqpd0uvmrCiSohaoxMgL+E5O\/eVoND8Il7ODcCRLSOXiARBG1TJD8mNM6JeoeM=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjBiYWQ5ZWRhMWM2YWU0ZDM4ZTQwNWYzYzlmNGE1YTcyIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/cmie.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88830fe elementor-widget elementor-widget-spacer\" data-id=\"88830fe\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-912c397 e-flex e-con-boxed e-con e-parent\" data-id=\"912c397\" data-element_type=\"container\" id=\"gradient\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-647e00a elementor-widget elementor-widget-spacer\" data-id=\"647e00a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Appels \u00e0 propositions Le Fonds de D\u00e9veloppement offre un soutien financier aux innovateurs, aux d\u00e9veloppeurs et aux \u00e9tablissements universitaires au Canada, sp\u00e9cifiquement dans le domaine des technologies radiopharmaceutiques et des isotopes m\u00e9dicaux. Ce financement est con\u00e7u pour acc\u00e9l\u00e9rer la progression des programmes en phase de d\u00e9marrage, cr\u00e9ant ainsi un pipeline continu pour le d\u00e9veloppement et &#8230; <a title=\"Appels \u00e0 propositions\" class=\"read-more\" href=\"https:\/\/cmie.ca\/fr\/appels-a-propositions\/\" aria-label=\"En savoir plus sur Appels \u00e0 propositions\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-684","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/pages\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":75,"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/pages\/684\/revisions"}],"predecessor-version":[{"id":4387,"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/pages\/684\/revisions\/4387"}],"wp:attachment":[{"href":"https:\/\/cmie.ca\/fr\/wp-json\/wp\/v2\/media?parent=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}